{"id":4969,"date":"2026-07-15T17:04:00","date_gmt":"2026-07-15T15:04:00","guid":{"rendered":"https:\/\/www.fuss-ev.de\/wuppertal\/?p=4969"},"modified":"2026-07-15T17:04:00","modified_gmt":"2026-07-15T15:04:00","slug":"wuppertal-fussgaenger-auf-cronenberger-strasse-von-mazda-erfasst-fahrer-fluechtet","status":"publish","type":"post","link":"https:\/\/www.fuss-ev.de\/wuppertal\/2026\/07\/15\/wuppertal-fussgaenger-auf-cronenberger-strasse-von-mazda-erfasst-fahrer-fluechtet\/","title":{"rendered":"Fu\u00dfg\u00e4nger erfasst &#8211; Unfallflucht auf der Cronenberger Stra\u00dfe!"},"content":{"rendered":"<h5>Ver\u00f6ffentlichung eines Polizeiberichtes &#8220;POL W: W Zeugen gesucht &#8211; Unfallflucht auf der Cronenberger Stra\u00dfe&#8221;- vom 15.07.2026 \u2013 11:07<\/h5>\n<p>Am 13.07.2026, gegen 16:50 Uhr, kam es auf der Cronenberger Stra\u00dfe zu einem Verkehrsunfall mit Flucht.<\/p>\n<p>Ein 51-j\u00e4hriger Mann wollte die Cronenberger Stra\u00dfe im Bereich des Jung-Stilling-Wegs \u00fcberqueren, als er von einem grauen Mazda 3 erfasst wurde, der von dem angrenzenden Supermarktparkplatz verbotswidrig links abgebogen war. Der bislang unbekannte Fahrer stieg kurz aus dem Mazda aus, schaute sich um und fuhr dann in Richtung S\u00fcden davon.<\/p>\n<p>Der Fl\u00fcchtige wird als circa 20 bis 30 Jahre alt und 1,80m bis 1,85m gro\u00df sowie blond beschrieben.<\/p>\n<p>Rettungskr\u00e4fte brachten den leichtverletzten 51-J\u00e4hrigen in ein Krankenhaus.<\/p>\n<p>Zeugen und Hinweisgeber werden gebeten, sich unter der 0202 \/ 284 0 bei der Polizei zu melden.<\/p>\n<hr \/>\n<p>Wir w\u00fcnschen der verletzten Frau alles Gute und eine baldige Genesung.<\/p>\n<p>Alle anderen beteiligen Personen m\u00f6gen den Unfall gut verkraften.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ver\u00f6ffentlichung eines Polizeiberichtes &#8220;POL W: W Zeugen gesucht &#8211; Unfallflucht auf der Cronenberger Stra\u00dfe&#8221;- vom 15.07.2026 \u2013 11:07 Am 13.07.2026, gegen 16:50 Uhr, kam es auf der Cronenberger Stra\u00dfe zu einem Verkehrsunfall mit Flucht. Ein [&hellip;]<\/p>\n","protected":false},"author":45,"featured_media":4681,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[8],"tags":[88,17,21,18,22,13],"class_list":["post-4969","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles","tag-cronenberger-strasse","tag-polizeibericht","tag-verkehr","tag-verkehrsunfall","tag-verletzter-fussgaenger","tag-wuppertal"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fu\u00dfg\u00e4nger erfasst - Unfallflucht auf der Cronenberger Stra\u00dfe! - Wuppertal - FUSS e.V.<\/title>\n<meta name=\"description\" content=\"Eine 18-J\u00e4hrige wurde in Wuppertal-Elberfeld von einem wei\u00dfen Cabriolet angefahren und leicht verletzt. Der Fahrer fl\u00fcchtete \u2013 Polizei sucht Zeugen. Auf der Cronenberger Stra\u00dfe in Wuppertal wurde ein 51-J\u00e4hriger von einem grauen Mazda 3 angefahren und leicht verletzt. Der Fahrer fl\u00fcchtete \u2013 die Polizei sucht Zeugen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fuss-ev.de\/wuppertal\/2026\/07\/15\/wuppertal-fussgaenger-auf-cronenberger-strasse-von-mazda-erfasst-fahrer-fluechtet\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fu\u00dfg\u00e4nger erfasst - Unfallflucht auf der Cronenberger Stra\u00dfe! - Wuppertal - FUSS e.V.\" \/>\n<meta property=\"og:description\" content=\"Eine 18-J\u00e4hrige wurde in Wuppertal-Elberfeld von einem wei\u00dfen Cabriolet angefahren und leicht verletzt. Der Fahrer fl\u00fcchtete \u2013 Polizei sucht Zeugen. Auf der Cronenberger Stra\u00dfe in Wuppertal wurde ein 51-J\u00e4hriger von einem grauen Mazda 3 angefahren und leicht verletzt. Der Fahrer fl\u00fcchtete \u2013 die Polizei sucht Zeugen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fuss-ev.de\/wuppertal\/2026\/07\/15\/wuppertal-fussgaenger-auf-cronenberger-strasse-von-mazda-erfasst-fahrer-fluechtet\/\" \/>\n<meta property=\"og:site_name\" content=\"Wuppertal - FUSS e.V.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fussverkehr.de\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T15:04:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fuss-ev.de\/wuppertal\/wp-content\/uploads\/sites\/20\/2025\/03\/Blaulicht-Polizei-klein-319x200-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"319\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"wolfhardwinkelstroeter\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"wolfhardwinkelstroeter\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fuss-ev.de\\\/wuppertal\\\/2026\\\/07\\\/15\\\/wuppertal-fussgaenger-auf-cronenberger-strasse-von-mazda-erfasst-fahrer-fluechtet\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fuss-ev.de\\\/wuppertal\\\/2026\\\/07\\\/15\\\/wuppertal-fussgaenger-auf-cronenberger-strasse-von-mazda-erfasst-fahrer-fluechtet\\\/\"},\"author\":{\"name\":\"wolfhardwinkelstroeter\",\"@id\":\"https:\\\/\\\/www.fuss-ev.de\\\/wuppertal\\\/#\\\/schema\\\/person\\\/c8db420c941076acab609d46a44c2dba\"},\"headline\":\"Fu\u00dfg\u00e4nger erfasst &#8211; Unfallflucht auf der Cronenberger Stra\u00dfe!\",\"datePublished\":\"2026-07-15T15:04:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fuss-ev.de\\\/wuppertal\\\/2026\\\/07\\\/15\\\/wuppertal-fussgaenger-auf-cronenberger-strasse-von-mazda-erfasst-fahrer-fluechtet\\\/\"},\"wordCount\":159,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fuss-ev.de\\\/wuppertal\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fuss-ev.de\\\/wuppertal\\\/2026\\\/07\\\/15\\\/wuppertal-fussgaenger-auf-cronenberger-strasse-von-mazda-erfasst-fahrer-fluechtet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fuss-ev.de\\\/wuppertal\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2025\\\/03\\\/Blaulicht-Polizei-klein-319x200-1.png\",\"keywords\":[\"Cronenberger Stra\u00dfe\",\"Polizeibericht\",\"Verkehr\",\"Verkehrsunfall\",\"verletzter Fu\u00dfg\u00e4nger\",\"Wuppertal\"],\"articleSection\":[\"Aktuelles\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fuss-ev.de\\\/wuppertal\\\/2026\\\/07\\\/15\\\/wuppertal-fussgaenger-auf-cronenberger-strasse-von-mazda-erfasst-fahrer-fluechtet\\\/\",\"url\":\"https:\\\/\\\/www.fuss-ev.de\\\/wuppertal\\\/2026\\\/07\\\/15\\\/wuppertal-fussgaenger-auf-cronenberger-strasse-von-mazda-erfasst-fahrer-fluechtet\\\/\",\"name\":\"Fu\u00dfg\u00e4nger erfasst - Unfallflucht auf der Cronenberger Stra\u00dfe! - Wuppertal - FUSS e.V.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fuss-ev.de\\\/wuppertal\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fuss-ev.de\\\/wuppertal\\\/2026\\\/07\\\/15\\\/wuppertal-fussgaenger-auf-cronenberger-strasse-von-mazda-erfasst-fahrer-fluechtet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fuss-ev.de\\\/wuppertal\\\/2026\\\/07\\\/15\\\/wuppertal-fussgaenger-auf-cronenberger-strasse-von-mazda-erfasst-fahrer-fluechtet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fuss-ev.de\\\/wuppertal\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2025\\\/03\\\/Blaulicht-Polizei-klein-319x200-1.png\",\"datePublished\":\"2026-07-15T15:04:00+00:00\",\"description\":\"Eine 18-J\u00e4hrige wurde in Wuppertal-Elberfeld von einem wei\u00dfen Cabriolet angefahren und leicht verletzt. Der Fahrer fl\u00fcchtete \u2013 Polizei sucht Zeugen. Auf der Cronenberger Stra\u00dfe in Wuppertal wurde ein 51-J\u00e4hriger von einem grauen Mazda 3 angefahren und leicht verletzt. Der Fahrer fl\u00fcchtete \u2013 die Polizei sucht Zeugen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fuss-ev.de\\\/wuppertal\\\/2026\\\/07\\\/15\\\/wuppertal-fussgaenger-auf-cronenberger-strasse-von-mazda-erfasst-fahrer-fluechtet\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fuss-ev.de\\\/wuppertal\\\/2026\\\/07\\\/15\\\/wuppertal-fussgaenger-auf-cronenberger-strasse-von-mazda-erfasst-fahrer-fluechtet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.fuss-ev.de\\\/wuppertal\\\/2026\\\/07\\\/15\\\/wuppertal-fussgaenger-auf-cronenberger-strasse-von-mazda-erfasst-fahrer-fluechtet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fuss-ev.de\\\/wuppertal\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2025\\\/03\\\/Blaulicht-Polizei-klein-319x200-1.png\",\"contentUrl\":\"https:\\\/\\\/www.fuss-ev.de\\\/wuppertal\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2025\\\/03\\\/Blaulicht-Polizei-klein-319x200-1.png\",\"width\":319,\"height\":200,\"caption\":\"Symbolbild Polizei Blaulicht\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fuss-ev.de\\\/wuppertal\\\/2026\\\/07\\\/15\\\/wuppertal-fussgaenger-auf-cronenberger-strasse-von-mazda-erfasst-fahrer-fluechtet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.fuss-ev.de\\\/wuppertal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fu\u00dfg\u00e4nger erfasst &#8211; Unfallflucht auf der Cronenberger Stra\u00dfe!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fuss-ev.de\\\/wuppertal\\\/#website\",\"url\":\"https:\\\/\\\/www.fuss-ev.de\\\/wuppertal\\\/\",\"name\":\"Wuppertal - FUSS e.V.\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fuss-ev.de\\\/wuppertal\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fuss-ev.de\\\/wuppertal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fuss-ev.de\\\/wuppertal\\\/#organization\",\"name\":\"Wuppertal - FUSS e.V.\",\"url\":\"https:\\\/\\\/www.fuss-ev.de\\\/wuppertal\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.fuss-ev.de\\\/wuppertal\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fuss-ev.de\\\/wuppertal\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2025\\\/01\\\/FUSS_Logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fuss-ev.de\\\/wuppertal\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2025\\\/01\\\/FUSS_Logo.jpg\",\"width\":2082,\"height\":979,\"caption\":\"Wuppertal - FUSS e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fuss-ev.de\\\/wuppertal\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fussverkehr.de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fuss-ev.de\\\/wuppertal\\\/#\\\/schema\\\/person\\\/c8db420c941076acab609d46a44c2dba\",\"name\":\"wolfhardwinkelstroeter\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/16984e6b0d78cf07ffe0a05dddfb00323db169803ed43e94c046b877250b7aa1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/16984e6b0d78cf07ffe0a05dddfb00323db169803ed43e94c046b877250b7aa1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/16984e6b0d78cf07ffe0a05dddfb00323db169803ed43e94c046b877250b7aa1?s=96&d=mm&r=g\",\"caption\":\"wolfhardwinkelstroeter\"},\"url\":\"https:\\\/\\\/www.fuss-ev.de\\\/wuppertal\\\/author\\\/wolfhardwinkelstroeter\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fu\u00dfg\u00e4nger erfasst - Unfallflucht auf der Cronenberger Stra\u00dfe! - Wuppertal - FUSS e.V.","description":"Eine 18-J\u00e4hrige wurde in Wuppertal-Elberfeld von einem wei\u00dfen Cabriolet angefahren und leicht verletzt. Der Fahrer fl\u00fcchtete \u2013 Polizei sucht Zeugen. Auf der Cronenberger Stra\u00dfe in Wuppertal wurde ein 51-J\u00e4hriger von einem grauen Mazda 3 angefahren und leicht verletzt. Der Fahrer fl\u00fcchtete \u2013 die Polizei sucht Zeugen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fuss-ev.de\/wuppertal\/2026\/07\/15\/wuppertal-fussgaenger-auf-cronenberger-strasse-von-mazda-erfasst-fahrer-fluechtet\/","og_locale":"de_DE","og_type":"article","og_title":"Fu\u00dfg\u00e4nger erfasst - Unfallflucht auf der Cronenberger Stra\u00dfe! - Wuppertal - FUSS e.V.","og_description":"Eine 18-J\u00e4hrige wurde in Wuppertal-Elberfeld von einem wei\u00dfen Cabriolet angefahren und leicht verletzt. Der Fahrer fl\u00fcchtete \u2013 Polizei sucht Zeugen. Auf der Cronenberger Stra\u00dfe in Wuppertal wurde ein 51-J\u00e4hriger von einem grauen Mazda 3 angefahren und leicht verletzt. Der Fahrer fl\u00fcchtete \u2013 die Polizei sucht Zeugen.","og_url":"https:\/\/www.fuss-ev.de\/wuppertal\/2026\/07\/15\/wuppertal-fussgaenger-auf-cronenberger-strasse-von-mazda-erfasst-fahrer-fluechtet\/","og_site_name":"Wuppertal - FUSS e.V.","article_publisher":"https:\/\/www.facebook.com\/fussverkehr.de","article_published_time":"2026-07-15T15:04:00+00:00","og_image":[{"width":319,"height":200,"url":"https:\/\/www.fuss-ev.de\/wuppertal\/wp-content\/uploads\/sites\/20\/2025\/03\/Blaulicht-Polizei-klein-319x200-1.png","type":"image\/png"}],"author":"wolfhardwinkelstroeter","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"wolfhardwinkelstroeter","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fuss-ev.de\/wuppertal\/2026\/07\/15\/wuppertal-fussgaenger-auf-cronenberger-strasse-von-mazda-erfasst-fahrer-fluechtet\/#article","isPartOf":{"@id":"https:\/\/www.fuss-ev.de\/wuppertal\/2026\/07\/15\/wuppertal-fussgaenger-auf-cronenberger-strasse-von-mazda-erfasst-fahrer-fluechtet\/"},"author":{"name":"wolfhardwinkelstroeter","@id":"https:\/\/www.fuss-ev.de\/wuppertal\/#\/schema\/person\/c8db420c941076acab609d46a44c2dba"},"headline":"Fu\u00dfg\u00e4nger erfasst &#8211; Unfallflucht auf der Cronenberger Stra\u00dfe!","datePublished":"2026-07-15T15:04:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fuss-ev.de\/wuppertal\/2026\/07\/15\/wuppertal-fussgaenger-auf-cronenberger-strasse-von-mazda-erfasst-fahrer-fluechtet\/"},"wordCount":159,"publisher":{"@id":"https:\/\/www.fuss-ev.de\/wuppertal\/#organization"},"image":{"@id":"https:\/\/www.fuss-ev.de\/wuppertal\/2026\/07\/15\/wuppertal-fussgaenger-auf-cronenberger-strasse-von-mazda-erfasst-fahrer-fluechtet\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fuss-ev.de\/wuppertal\/wp-content\/uploads\/sites\/20\/2025\/03\/Blaulicht-Polizei-klein-319x200-1.png","keywords":["Cronenberger Stra\u00dfe","Polizeibericht","Verkehr","Verkehrsunfall","verletzter Fu\u00dfg\u00e4nger","Wuppertal"],"articleSection":["Aktuelles"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.fuss-ev.de\/wuppertal\/2026\/07\/15\/wuppertal-fussgaenger-auf-cronenberger-strasse-von-mazda-erfasst-fahrer-fluechtet\/","url":"https:\/\/www.fuss-ev.de\/wuppertal\/2026\/07\/15\/wuppertal-fussgaenger-auf-cronenberger-strasse-von-mazda-erfasst-fahrer-fluechtet\/","name":"Fu\u00dfg\u00e4nger erfasst - Unfallflucht auf der Cronenberger Stra\u00dfe! - Wuppertal - FUSS e.V.","isPartOf":{"@id":"https:\/\/www.fuss-ev.de\/wuppertal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fuss-ev.de\/wuppertal\/2026\/07\/15\/wuppertal-fussgaenger-auf-cronenberger-strasse-von-mazda-erfasst-fahrer-fluechtet\/#primaryimage"},"image":{"@id":"https:\/\/www.fuss-ev.de\/wuppertal\/2026\/07\/15\/wuppertal-fussgaenger-auf-cronenberger-strasse-von-mazda-erfasst-fahrer-fluechtet\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fuss-ev.de\/wuppertal\/wp-content\/uploads\/sites\/20\/2025\/03\/Blaulicht-Polizei-klein-319x200-1.png","datePublished":"2026-07-15T15:04:00+00:00","description":"Eine 18-J\u00e4hrige wurde in Wuppertal-Elberfeld von einem wei\u00dfen Cabriolet angefahren und leicht verletzt. Der Fahrer fl\u00fcchtete \u2013 Polizei sucht Zeugen. Auf der Cronenberger Stra\u00dfe in Wuppertal wurde ein 51-J\u00e4hriger von einem grauen Mazda 3 angefahren und leicht verletzt. Der Fahrer fl\u00fcchtete \u2013 die Polizei sucht Zeugen.","breadcrumb":{"@id":"https:\/\/www.fuss-ev.de\/wuppertal\/2026\/07\/15\/wuppertal-fussgaenger-auf-cronenberger-strasse-von-mazda-erfasst-fahrer-fluechtet\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fuss-ev.de\/wuppertal\/2026\/07\/15\/wuppertal-fussgaenger-auf-cronenberger-strasse-von-mazda-erfasst-fahrer-fluechtet\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.fuss-ev.de\/wuppertal\/2026\/07\/15\/wuppertal-fussgaenger-auf-cronenberger-strasse-von-mazda-erfasst-fahrer-fluechtet\/#primaryimage","url":"https:\/\/www.fuss-ev.de\/wuppertal\/wp-content\/uploads\/sites\/20\/2025\/03\/Blaulicht-Polizei-klein-319x200-1.png","contentUrl":"https:\/\/www.fuss-ev.de\/wuppertal\/wp-content\/uploads\/sites\/20\/2025\/03\/Blaulicht-Polizei-klein-319x200-1.png","width":319,"height":200,"caption":"Symbolbild Polizei Blaulicht"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fuss-ev.de\/wuppertal\/2026\/07\/15\/wuppertal-fussgaenger-auf-cronenberger-strasse-von-mazda-erfasst-fahrer-fluechtet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.fuss-ev.de\/wuppertal\/"},{"@type":"ListItem","position":2,"name":"Fu\u00dfg\u00e4nger erfasst &#8211; Unfallflucht auf der Cronenberger Stra\u00dfe!"}]},{"@type":"WebSite","@id":"https:\/\/www.fuss-ev.de\/wuppertal\/#website","url":"https:\/\/www.fuss-ev.de\/wuppertal\/","name":"Wuppertal - FUSS e.V.","description":"","publisher":{"@id":"https:\/\/www.fuss-ev.de\/wuppertal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fuss-ev.de\/wuppertal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.fuss-ev.de\/wuppertal\/#organization","name":"Wuppertal - FUSS e.V.","url":"https:\/\/www.fuss-ev.de\/wuppertal\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.fuss-ev.de\/wuppertal\/#\/schema\/logo\/image\/","url":"https:\/\/www.fuss-ev.de\/wuppertal\/wp-content\/uploads\/sites\/20\/2025\/01\/FUSS_Logo.jpg","contentUrl":"https:\/\/www.fuss-ev.de\/wuppertal\/wp-content\/uploads\/sites\/20\/2025\/01\/FUSS_Logo.jpg","width":2082,"height":979,"caption":"Wuppertal - FUSS e.V."},"image":{"@id":"https:\/\/www.fuss-ev.de\/wuppertal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fussverkehr.de"]},{"@type":"Person","@id":"https:\/\/www.fuss-ev.de\/wuppertal\/#\/schema\/person\/c8db420c941076acab609d46a44c2dba","name":"wolfhardwinkelstroeter","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/16984e6b0d78cf07ffe0a05dddfb00323db169803ed43e94c046b877250b7aa1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/16984e6b0d78cf07ffe0a05dddfb00323db169803ed43e94c046b877250b7aa1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/16984e6b0d78cf07ffe0a05dddfb00323db169803ed43e94c046b877250b7aa1?s=96&d=mm&r=g","caption":"wolfhardwinkelstroeter"},"url":"https:\/\/www.fuss-ev.de\/wuppertal\/author\/wolfhardwinkelstroeter\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 20:08:35","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.fuss-ev.de\/wuppertal\/wp-json\/wp\/v2\/posts\/4969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fuss-ev.de\/wuppertal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fuss-ev.de\/wuppertal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fuss-ev.de\/wuppertal\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fuss-ev.de\/wuppertal\/wp-json\/wp\/v2\/comments?post=4969"}],"version-history":[{"count":1,"href":"https:\/\/www.fuss-ev.de\/wuppertal\/wp-json\/wp\/v2\/posts\/4969\/revisions"}],"predecessor-version":[{"id":4970,"href":"https:\/\/www.fuss-ev.de\/wuppertal\/wp-json\/wp\/v2\/posts\/4969\/revisions\/4970"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fuss-ev.de\/wuppertal\/wp-json\/wp\/v2\/media\/4681"}],"wp:attachment":[{"href":"https:\/\/www.fuss-ev.de\/wuppertal\/wp-json\/wp\/v2\/media?parent=4969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fuss-ev.de\/wuppertal\/wp-json\/wp\/v2\/categories?post=4969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fuss-ev.de\/wuppertal\/wp-json\/wp\/v2\/tags?post=4969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}